{"id":5752,"date":"2025-12-09T23:55:40","date_gmt":"2025-12-09T23:55:40","guid":{"rendered":"https:\/\/anbc.org.br\/?page_id=5752"},"modified":"2025-12-09T23:55:40","modified_gmt":"2025-12-09T23:55:40","slug":"nota-de-credito-en-brasil","status":"publish","type":"page","link":"https:\/\/anbc.org.br\/es\/nota-de-credito-en-brasil\/","title":{"rendered":"Nota de cr\u00e9dito en Brasil"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><section data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-parallax-image=\"https:\/\/anbc.org.br\/wp-content\/themes\/genemy\/images\/banner-1.jpg\" data-opacity=\"1\" data-size=\"cover\" data-width=\"100%\" data-position=\"cover\" data-repeat=\"cover\" data-attachment=\"inherit\" class=\"vc_section wide-60 bg-tra m-top-default m-bottom-default p-top-default p-bottom-default vc_custom_1705004699980 bg-inherit\"><div class=\"container\"><div class=\"vc_row wpb_row vc_row-fluid genemy-default bg-tra vc_custom_1705004809308\"><div class=\"wpb_column vc_column_container vc_col-sm-2 bg-tra\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8 bg-tra\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2 bg-tra\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid genemy-default bg-tra\"><div class=\"wpb_column vc_column_container vc_col-sm-12 bg-tra\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><section id=\"blog\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-parallax-image=\"https:\/\/anbc.org.br\/wp-content\/themes\/genemy\/images\/banner-1.jpg\" data-opacity=\"1\" data-size=\"cover\" data-width=\"100%\" data-position=\"cover\" data-repeat=\"cover\" data-attachment=\"inherit\" class=\"vc_section wide-60 bg-white m-top-default m-bottom-default p-top-default p-bottom-default vc_custom_1702769671289 bg-inherit\"><div class=\"container\"><div class=\"vc_row wpb_row vc_row-fluid genemy-default bg-tra\"><div class=\"wpb_column vc_column_container vc_col-sm-12 bg-tra\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Lea el cuadro siguiente y descargue el archivo.<\/h2>\n<h3>Descargar: Nota de cr\u00e9dito en Brasil<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5750-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5750\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/5752#wpcf7-f5750-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/5752#wpcf7-f5750-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5750\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5750-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-holder ind-20\">\n\t<div  class=\"row contact-form contact-form-2\">\n\t\t<div id=\"input-email\" class=\"col-lg-6\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Introduzca su direcci\u00f3n de correo electr\u00f3nico\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-297\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-297\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Autorizo el uso de mis datos personales para el env\u00edo de comunicaciones de ANBC.<\/span><\/label><\/span><\/span><\/span>\n\t\t<\/p>\n\t\t<div class=\"col-lg-12 m-top-10 form-btn\">\n\t\t\t<p><button type=\"submit\" class=\"btn btn-md submit btn-arrow wpcf7-form-control wpcf7-submit\"><span>Descargar <i class=\"fas fa-angle-double-right\"><\/i><\/span><\/button>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-lg-12 contact-form-msg\">\n\t\t<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid genemy-default bg-tra\"><div class=\"wpb_column vc_column_container vc_col-sm-12 bg-tra\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Llene el campo a continuaci\u00f3n y descargue el archivo. Download: Nota de Cr\u00e9dito en Brasil &nbsp; &nbsp; Autorizo el uso de mis datos personales para el env\u00edo de comunicaciones de ANBC. Descargar","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/onepage-template.php","meta":{"_seopress_titles_title":"Download: Nota de Cr\u00e9dito en Brasil","_seopress_titles_desc":"Download: Nota de Cr\u00e9dito en Brasil","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"Nota de Cr\u00e9dito","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[{"url":"","title":"","desc":"","thumbnail":"","duration":"","rating":"","view_count":"","tag":""}],"_seopress_pro_schemas_manual":[{"_seopress_pro_rich_snippets_type":"none"}],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"pgc_sgb_lightbox_settings":"","footnotes":""},"class_list":["post-5752","page","type-page","status-publish","hentry","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/anbc.org.br\/es\/wp-json\/wp\/v2\/pages\/5752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anbc.org.br\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anbc.org.br\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anbc.org.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anbc.org.br\/es\/wp-json\/wp\/v2\/comments?post=5752"}],"version-history":[{"count":1,"href":"https:\/\/anbc.org.br\/es\/wp-json\/wp\/v2\/pages\/5752\/revisions"}],"predecessor-version":[{"id":5754,"href":"https:\/\/anbc.org.br\/es\/wp-json\/wp\/v2\/pages\/5752\/revisions\/5754"}],"wp:attachment":[{"href":"https:\/\/anbc.org.br\/es\/wp-json\/wp\/v2\/media?parent=5752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}